{"id":3165,"date":"2025-08-06T09:36:08","date_gmt":"2025-08-06T09:36:08","guid":{"rendered":"https:\/\/platform.highres-project.eu\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita"},"modified":"2025-09-22T11:14:07","modified_gmt":"2025-09-22T11:14:07","slug":"3-1-cultura-dellinnovazione-e-della-creativita","status":"publish","type":"chapter","link":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita","title":{"rendered":"3.1 Cultura dell&#8217;innovazione e della creativit\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3165\" class=\"elementor elementor-3165 elementor-2288\" data-elementor-post-type=\"chapter\">\n\t\t\t\t<div class=\"elementor-element elementor-element-489775a e-flex e-con-boxed e-con e-parent\" data-id=\"489775a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c81229a elementor-widget elementor-widget-text-editor\" data-id=\"c81229a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;innovazione nelle nostre comunit\u00e0 va oltre l&#8217;introduzione di nuove tecnologie o tendenze. Inizia con l&#8217;ascolto sincero, la valorizzazione delle conoscenze locali e la costruzione insieme di soluzioni legate alle esperienze di vita reale. Ispirandosi alle idee di Paulo Freire (2014) e Ren\u00e9 Barbier (1997), innovazione significa dialogare con il territorio e la sua gente, partendo dall&#8217;ascolto etico ed empatico come primo passo verso il cambiamento.  <\/p><p>In questo modo, una cultura dell&#8217;innovazione non significa solo inventare qualcosa di nuovo, implica anche riportare in auge le tradizioni, ripensare le abitudini quotidiane e utilizzare diversi tipi di conoscenze per affrontare sfide comuni. La creativit\u00e0 \u00e8 vista come qualcosa che costruiamo insieme nel tempo, supportati da spazi che accolgono l&#8217;immaginazione, la sperimentazione, gli errori e l&#8217;apprendimento lungo il percorso.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364eefa dce_masking-none elementor-widget elementor-widget-image\" data-id=\"364eefa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2-1024x683.jpeg\" class=\"attachment-large size-large wp-image-2292\" alt=\"\" srcset=\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2-1024x683.jpeg 1024w, https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2-300x200.jpeg 300w, https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2-768x512.jpeg 768w, https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg 1366w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fig. 2. Co-criacao na aldeia. Processo criativo da obra de Folgarosa. Fonte: <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.museunaaldeia.pt\/obras\/folgarosa-vai-ao-museu-de-arte-popular-portuguesa\/\">SAMP-11<\/a>  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341849c elementor-widget elementor-widget-text-editor\" data-id=\"341849c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Riferendosi all&#8217;idea di una Cultura dell&#8217;Innovazione nei musei (Eid &amp; Forstrom, 2021), vediamo che quando gli ambienti sono aperti alla partecipazione, alla collaborazione e alla diversit\u00e0, incoraggiano le persone a partecipare e a diventare pi\u00f9 flessibili. Ma affinch\u00e9 l&#8217;innovazione prenda davvero forma, \u00e8 importante avere un forte sostegno istituzionale che aiuti a organizzare, mantenere e guidare questi sforzi. <\/p><p>Ecco perch\u00e9 la creazione di un Dipartimento Innovazione pu\u00f2 fare una grande differenza: un team dedicato a questo lavoro, idealmente con un proprio budget e gli strumenti adeguati per promuovere l&#8217;ascolto attivo, gestire le proposte e seguire chiaramente i progressi delle nuove idee.<\/p><p>Incoraggiare una cultura dell&#8217;innovazione significa costruire fiducia, riconoscere il potere della creativit\u00e0 collettiva e scegliere una leadership partecipativa come mezzo per apportare cambiamenti positivi, con attenzione, apertura e il coraggio di ricominciare da capo sulla base di esperienze reali.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":2292,"template":"","meta":{"_acf_changed":false},"class_list":["post-3165","chapter","type-chapter","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3.1 Cultura dell&#039;innovazione e della creativit\u00e0 - HIGHRES Platform<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3.1 Cultura dell&#039;innovazione e della creativit\u00e0 - HIGHRES Platform\" \/>\n<meta property=\"og:description\" content=\"L&#8217;innovazione nelle nostre comunit\u00e0 va oltre l&#8217;introduzione di nuove tecnologie o tendenze. Inizia con l&#8217;ascolto sincero, la valorizzazione delle conoscenze locali e la costruzione insieme di soluzioni legate alle esperienze di vita reale. Ispirandosi alle idee di Paulo Freire (2014) e Ren\u00e9 Barbier (1997), innovazione significa dialogare con il territorio e la sua gente, partendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita\" \/>\n<meta property=\"og:site_name\" content=\"HIGHRES Platform\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T11:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita\",\"url\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita\",\"name\":\"3.1 Cultura dell'innovazione e della creativit\u00e0 - HIGHRES Platform\",\"isPartOf\":{\"@id\":\"https:\/\/platform.highres-project.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage\"},\"image\":{\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage\"},\"thumbnailUrl\":\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg\",\"datePublished\":\"2025-08-06T09:36:08+00:00\",\"dateModified\":\"2025-09-22T11:14:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage\",\"url\":\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg\",\"contentUrl\":\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg\",\"width\":1366,\"height\":911},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/platform.highres-project.eu\/it\/home\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3.1 Cultura dell&#8217;innovazione e della creativit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/platform.highres-project.eu\/#website\",\"url\":\"https:\/\/platform.highres-project.eu\/\",\"name\":\"HIGHRES Platform\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/platform.highres-project.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/platform.highres-project.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/platform.highres-project.eu\/#organization\",\"name\":\"HIGHRES Platform\",\"url\":\"https:\/\/platform.highres-project.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/platform.highres-project.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/03\/HIGHRES-logo.png\",\"contentUrl\":\"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/03\/HIGHRES-logo.png\",\"width\":4096,\"height\":1177,\"caption\":\"HIGHRES Platform\"},\"image\":{\"@id\":\"https:\/\/platform.highres-project.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3.1 Cultura dell'innovazione e della creativit\u00e0 - HIGHRES Platform","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita","og_locale":"it_IT","og_type":"article","og_title":"3.1 Cultura dell'innovazione e della creativit\u00e0 - HIGHRES Platform","og_description":"L&#8217;innovazione nelle nostre comunit\u00e0 va oltre l&#8217;introduzione di nuove tecnologie o tendenze. Inizia con l&#8217;ascolto sincero, la valorizzazione delle conoscenze locali e la costruzione insieme di soluzioni legate alle esperienze di vita reale. Ispirandosi alle idee di Paulo Freire (2014) e Ren\u00e9 Barbier (1997), innovazione significa dialogare con il territorio e la sua gente, partendo [&hellip;]","og_url":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita","og_site_name":"HIGHRES Platform","article_modified_time":"2025-09-22T11:14:07+00:00","og_image":[{"width":1366,"height":911,"url":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita","url":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita","name":"3.1 Cultura dell'innovazione e della creativit\u00e0 - HIGHRES Platform","isPartOf":{"@id":"https:\/\/platform.highres-project.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage"},"image":{"@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage"},"thumbnailUrl":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg","datePublished":"2025-08-06T09:36:08+00:00","dateModified":"2025-09-22T11:14:07+00:00","breadcrumb":{"@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#primaryimage","url":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg","contentUrl":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/08\/2.jpeg","width":1366,"height":911},{"@type":"BreadcrumbList","@id":"https:\/\/platform.highres-project.eu\/it\/chapter\/3-1-cultura-dellinnovazione-e-della-creativita#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/platform.highres-project.eu\/it\/home"},{"@type":"ListItem","position":2,"name":"3.1 Cultura dell&#8217;innovazione e della creativit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/platform.highres-project.eu\/#website","url":"https:\/\/platform.highres-project.eu\/","name":"HIGHRES Platform","description":"","publisher":{"@id":"https:\/\/platform.highres-project.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/platform.highres-project.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/platform.highres-project.eu\/#organization","name":"HIGHRES Platform","url":"https:\/\/platform.highres-project.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/platform.highres-project.eu\/#\/schema\/logo\/image\/","url":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/03\/HIGHRES-logo.png","contentUrl":"https:\/\/platform.highres-project.eu\/wp-content\/uploads\/2025\/03\/HIGHRES-logo.png","width":4096,"height":1177,"caption":"HIGHRES Platform"},"image":{"@id":"https:\/\/platform.highres-project.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/chapter\/3165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/chapter"}],"about":[{"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/types\/chapter"}],"version-history":[{"count":1,"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/chapter\/3165\/revisions"}],"predecessor-version":[{"id":3166,"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/chapter\/3165\/revisions\/3166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/media\/2292"}],"wp:attachment":[{"href":"https:\/\/platform.highres-project.eu\/it\/wp-json\/wp\/v2\/media?parent=3165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}